{"id":1383,"date":"2017-06-14T07:15:23","date_gmt":"2017-06-14T07:15:23","guid":{"rendered":"http:\/\/xbodyworld.com\/?page_id=1383"},"modified":"2021-01-04T19:08:22","modified_gmt":"2021-01-04T18:08:22","slug":"xbody-actiwave","status":"publish","type":"page","link":"https:\/\/es.xbodyworld.com\/es\/xbody-actiwave\/","title":{"rendered":"XBody Actiwave"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"headerpost first section\">\n\n\t<div class=\"slide w-slide no-bg post-1384 post-debug-1384\" style=\"transform: translateX(0px); opacity: 1;\">\n\t\t<div class=\"vertical-center-left wide-container\">\n\t\t\t<div class=\"content-wrapper-50\">\n\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone size-medium wp-image-125\" src=\"\/wp-content\/uploads\/2017\/05\/actiwave-logo-300x32.png\" alt=\"\" width=\"300\" height=\"32\" srcset=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/actiwave-logo-300x32.png 300w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/actiwave-logo.png 383w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h1>EL H\u00cdBRIDO<\/h1>\n<p>El primer dispositivo EMS h\u00edbrido del mundo que permite entrenar con y sin cable al mismo tiempo. <strong> Actiwave se dise\u00f1\u00f3 para adaptarse a cualquier necesidad de entrenamiento de EMS <\/strong> y a cualquier modelo de negocio, y ofrece oportunidades de ingresos \u00fanicas.<\/p>\n<p><strong> Multiplique sus ingresos con sesiones de entrenamientos en grupo <\/strong> para hasta 6 clientes y duplique la facturaci\u00f3n de su microstudio EMS con no solo una, sino 2 o m\u00e1s sesiones de entrenamientos al mismo tiempo con un solo dispositivo.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"content-wrapper-50 full-height\">\n\t\t\t\t\t\t<img class=\"full-width-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/5-actiwave.png\" >\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"bottom-border section\"><div class=\"breadcrumbs-wrapper\"><a class=\"breadcrumbs-link\" href=\"https:\/\/es.xbodyworld.com\/es\" rel=\"nofollow\" >Home<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-1396\">\n\t<div class=\"regular-container\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">BENEFICIOS DE ACTIWAVE<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">El primer y \u00fanico dispositivo EMS h\u00edbrido del mundo<\/h3><p>XBody Actiwave es el siguiente paso en la evoluci\u00f3n de las soluciones EMS. Es el primer y \u00fanico dispositivo de entrenamiento EMS en el mundo que es <strong> simult\u00e1neamente capaz de entrenamiento con cable e inal\u00e1mbrico<\/strong>.<\/p>\n<p>XBody Actiwave se desarroll\u00f3 para dar la libertad a los estudios de utilizar cualquier m\u00e9todo de entrenamiento que deseen, para que puedan construir su propio negocio como lo deseen. Que sea entrenamiento personal con cable, entrenamiento grupal inal\u00e1mbrico, funcional, para deportivos espec\u00edficos, entrenamiento en interiores o al aire libre, <strong> Actiwave sigue siendo el \u00fanico dispositivo EMS capaz de adaptarse a todos estos m\u00e9todos de entrenamiento. <\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id: WOqR_sJnw9I -->\t\t\t\t\t\t\t\t<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: WOqR_sJnw9I -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/WOqR_sJnw9I?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/51-shopinshop.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Duplique su facturaci\u00f3n con un solo dispositivo<\/h3>\n\t\t\t\t\t\t\t<p>La incomparable capacidad h\u00edbrida de Actiwave permite a los propietarios de estudios programar <strong> entrenamientos cableados e inal\u00e1mbricos al mismo tiempo con un solo dispositivo<\/strong>, duplicando as\u00ed su facturaci\u00f3n y efectividad.<\/p>\n<p>Si bien necesitar\u00eda dos dispositivos EMS tradicionales para hacer lo mismo, con XBody Actiwave solo necesitar\u00e1 uno. <strong> Ahorre en el costo de comprar un segundo dispositivo EMS <\/strong> y gane m\u00e1s con esta capacidad.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Multiplice sus ingresos con el entrenamiento grupal<\/h3><p>Cuando tenga un Actiwave en su estudio, <strong> se abrir\u00e1n nuevas oportunidades comerciales <\/strong>. \u00bfPor qu\u00e9 entrenar a un solo cliente, cuando podr\u00eda entrenar hasta 6 clientes al mismo tiempo y multiplicar sus ingresos?<\/p>\n<p>Con XBody Actiwave, puede utilizar su funci\u00f3n de entrenamiento grupal inal\u00e1mbrico para <strong> entrenar a varios clientes al mismo tiempo <\/strong> sin dejar de prestar atenci\u00f3n y configuraci\u00f3n individual a cada cliente. <strong> Gane m\u00e1s dinero, ahorre costes y utilice sus entrenadores de forma eficaz. <\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id: a3fBM56HYVc -->\t\t\t\t\t\t\t\t<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: a3fBM56HYVc -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/a3fBM56HYVc?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/09\/XBody-Point-Setup-B.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">\u00bfC\u00f3mo funciona el Actiwave?<\/h3>\n\t\t\t\t\t\t\t<p>Nuestro equipo de desarrollo de productos interno ha inventado y elaborado una <strong> soluci\u00f3n \u00fanica y eficaz para el entrenamiento en grupo inal\u00e1mbrico<\/strong>. Funciona en una red segura y separada proporcionada por el XBody Point que conecta el dispositivo Actiwave y las unidades Actiwear. Con un Actiwave puede entrenar a 6 clientes inal\u00e1mbricos (con 6 Actiwears) o 5 clientes inal\u00e1mbricos (con 5 Actiwears) m\u00e1s un cliente con una conexi\u00f3n por cable a la unidad principal, \u00a1depende de usted y de sus preferencias!<\/p>\n<p>Nuestro XBody Point tiene sus propios canales separados, y la configuraci\u00f3n de la red se puede optimizar f\u00e1cilmente en caso de que haya alguna interferencia con otros dispositivos inal\u00e1mbricos en el \u00e1rea.<\/p>\n<p>Nuestro Actiwear es un mini dispositivo EMS en s\u00ed mismo, una vez que haya ajustado la configuraci\u00f3n con el Actiwave, se sincroniza y puede funcionar solo, lo que significa que puede entrenar <strong> sin l\u00edmites de distancia entre Actiwave y Actiwear <\/strong>, y explorar las emocionantes posibilidades que ofrece nuestra funci\u00f3n Go Out.<\/p>\n<p>Si tiene conexi\u00f3n a Internet, tambi\u00e9n tiene la posibilidad de conectarse al servicio XBody Online.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  style=\"background: #2b353a;\" class=\"margins section xbody-changingside post-1399 colored-bg gradient\">\n\t<div class=\"regular-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont dark intro\">\n\t\t\t\t\t\t\t<h3 class=\"story-header dark\">El campe\u00f3n indiscutido<\/h3><p>XBody Actiwave representa <strong> el siguiente paso evolutivo <\/strong> en la industria de EMS.<\/p>\n<p>Con funcionalidad h\u00edbrida por cable e inal\u00e1mbrica, entrenamientos funcionales y espec\u00edficos para deportes, capacidades para interiores y exteriores, una pantalla t\u00e1ctil de 15 &#8220;, programas de entrenamiento integrados con actualizaciones de software regulares y muchas caracter\u00edsticas nuevas, este <strong> dispositivo EMS galardonado <\/strong> se erige como el pin\u00e1culo de los logros en la tecnolog\u00eda EMS y abre oportunidades comerciales nunca antes vistas.<\/p>\n<p>Si desea un dispositivo EMS que haya sido <strong> dise\u00f1ado para ayudar a que su negocio tenga \u00e9xito y crecer,<\/strong> Actiwave le brindar\u00e1 una libertad incomparable para administrar su negocio como desee y ofrecer cualquier m\u00e9todo de entrenamiento a sus clientes.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"\/es\/contact-us\/\">Obtener una cotizaci\u00f3n<\/a>\n\t\t\t<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-3823\" src=\"\/wp-content\/uploads\/2017\/05\/poznan-106x104.png\" alt=\"\" width=\"106\" height=\"104\" \/><img loading=\"lazy\" class=\"alignnone wp-image-3915\" src=\"\/wp-content\/uploads\/2017\/06\/sport-and-russia-136x159.png\" alt=\"\" width=\"97\" height=\"113\" \/><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/51-actiwave-champion-e1504182017685.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins no-margin-bottom noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h2 style=\"text-align: center\">CARACTER\u00cdSTICAS DE ACTIWAVE <\/h2>\n<p style=\"text-align: center\">Maximice su facturaci\u00f3n con nuestro dispositivo potente, vers\u00e1til y eficiente. <\/p>\n<\/div>\n\t\t\t\t\t<\/div><div class=\"threecolumn margins section light notopspace nobottomspace\">\n    <div class=\"wide-container\">\n        <div class=\"icon-card-section\">\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"aligncenter wp-image-4167\" src=\"\/wp-content\/uploads\/2017\/06\/wireless-wired.png\" alt=\"\" width=\"209\" height=\"100\" \/><\/p>\n<h4>El h\u00edbrido: entrenamiento cableado e inal\u00e1mbrico<\/h4>\n<p>El entrenamiento con cable es \u00f3ptimo para el entrenamiento EMS cl\u00e1sico con ejercicios simplificados. El entrenamiento inal\u00e1mbrico te brinda las posibilidades y total libertad para todo tipo de movimientos espec\u00edficos o funcionales del deporte, <strong> incluso puedes salir a correr con la <strong> funci\u00f3n inal\u00e1mbrica Go-Out <\/strong> de XBody.<\/strong><\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"aligncenter wp-image-4169\" src=\"\/wp-content\/uploads\/2017\/06\/dual-program-mode.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>Entrenamiento dual &#8211; Dos entrenamientos en un dispositivo<\/h4>\n<p>Thanks to Actiwave&#8217;s advanced technology, strengthening and cardio trainings can be performed at the same time, maximizing the utilization of a single device and speeding up turnover.\u00a0<strong>One Actiwave can replace two traditional EMS devices.<\/strong><\/p>\n<p>Gracias a la avanzada tecnolog\u00eda de Actiwave, el fortalecimiento y los entrenamientos cardiovasculares se pueden realizar al mismo tiempo, maximizando la utilizaci\u00f3n de un solo dispositivo y acelerando la rotaci\u00f3n.<strong>\u00a0Un Actiwave puede reemplazar dos dispositivos EMS tradicionales.<\/strong><\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"aligncenter wp-image-4171\" src=\"\/wp-content\/uploads\/2017\/06\/individual-trainings.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Programas de entrenamiento individuales o sincronizados para 1 a 6 clientes<\/h4>\n<p>Configure diferentes programas de entrenamiento y <strong> elija la configuraci\u00f3n adecuada para cada uno de sus clientes <\/strong> en el grupo. Modifique la configuraci\u00f3n individualmente durante el entrenamiento si es necesario, brindando a sus clientes experiencia de entrenamiento personal incluso durante las sesiones grupales utilizando nuestras rutinas de operaci\u00f3n profesionales.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"aligncenter wp-image-4173\" src=\"\/wp-content\/uploads\/2017\/06\/late-checkin.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4><strong>Opci\u00f3n Separar sesiones &amp; Registro tarde<\/strong><\/h4>\n<p>Nuestro equipo de desarrollo lanza regularmente nuevas caracter\u00edsticas en sus actualizaciones de software para que siempre pueda tener la mejor tecnolog\u00eda. Con algunas de estas actualizaciones importantes, ahora puede proponer una o m\u00faltiples sesiones separadas durante los entrenamientos de grupo, lo que significa que<strong> puede dar seis entrenamientos separados al mismo tiempo<\/strong>. Usando la &#8220;opci\u00f3n de Registro tarde&#8221; puede agregar m\u00e1s clientes al grupo continuamente, sin tener que detener el entrenamiento de los otros clientes, lo que facilita la optimizaci\u00f3n del uso de sus dispositivos.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4265 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/virtual-trainer-100x100.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4><strong> Programa de entrenador virtual<br \/>\n<\/strong><\/h4>\n<p style=\"text-align: left;\">El programa de entrenador virtual integrado garantiza que los entrenamientos se optimicen y los ejercicios se implementen de la manera correcta, <strong> sin la necesidad de que el entrenador haga los ejercicios con los clientes &lt;\/ strong &gt;. El uso del programa de entrenador virtual permite a los entrenadores concentrarse en la posici\u00f3n, la postura y el desempe\u00f1o de los clientes incluso durante una sesi\u00f3n de grupo con la proyecci\u00f3n del programa en cualquier pantalla adicional (televisor grande o proyector). <\/strong><\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4258 aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/6-users.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Entrenamiento en grupo inal\u00e1mbrico confiable y eficaz<\/h4>\n<p>EMS como m\u00e9todo de fitness grupal es un servicio <strong> nuevo, revolucionario y probado que aumenta el ROI <\/strong> que se puede implementar en todo tipo de empresas, desde microstudios hasta grandes franquicias de gimnasios. \u00a1La efectividad y confiabilidad de nuestro concepto se demostr\u00f3 en el FIBO 2017 con m\u00e1s de 500 sesiones de entrenamiento en un fin de semana!<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/div><div class=\"maybegluetobottom margins section\"><div class=\"regular-container\"><div class=\"button-only story-section\"><div style=\"text-align: center; width: 100%;\"  class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"\/es\/contact-us\/\">Obtener una cotizaci\u00f3n<\/a>\n\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"accent-bg margins no-margin-bottom noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h2 class=\"section-heading\">ABRE SU ESTUDIO DE ENTRENAMIENTO EMS CON XBODY ACTIWAVE<\/h2>\n<div class=\"paragraphcont\">\n<h4 class=\"story-header\" style=\"text-align: center\">Soluci\u00f3n vers\u00e1til para adaptarse a un negocio en crecimiento y satisfacer m\u00faltiples necesidades<\/h4>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n<div  class=\"margins section xbody-changingside post- accent-bg notopspace\">\n\t<div class=\"wide-container\">\n\t\t\t\t\t\n\t<\/div>\n<\/div>\n<div  class=\"margins section xbody-changingside post-1421  nobottomspace\">\n\t<div class=\"wide-container nobottomspace\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">VENTAJAS COMERCIALES DE XBODY ACTIWAVE<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Dise\u00f1ado para hacer su negocio exitoso.<\/h3><table class=\"nonmax csptable\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" class=\"alignleft wp-image-4177\" src=\"\/wp-content\/uploads\/2017\/06\/51-doubleturnover.png\" alt=\"\" width=\"84\" height=\"78\" \/><\/td>\n<td><strong> DOBLE SU FACTURACI\u00d3N <\/strong><br \/>\nLas funciones de entrenamiento grupal y dual de Actiwave <strong> le abrir\u00e1n oportunidades comerciales incomparables <\/strong>, que pueden duplicar o incluso multiplicar sus ingresos.<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"alignleft wp-image-4178\" src=\"\/wp-content\/uploads\/2017\/06\/51-growstudio.png\" alt=\"\" width=\"80\" height=\"80\" \/><\/td>\n<td><strong> HAZ CRECER TU ESTUDIO <\/strong><br \/>\nActiwave fue dise\u00f1ado para que pueda ofrecer el m\u00e1ximo nivel de flexibilidad para su negocio. Haga crecer su clientela con entrenamientos grupales y <strong> pruebe diferentes m\u00e9todos de entrenamiento <\/strong> gracias a la tecnolog\u00eda h\u00edbrida para encontrar la que mejor se adapte a su negocio.<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"alignleft wp-image-4180\" src=\"\/wp-content\/uploads\/2017\/06\/51-top.png\" alt=\"\" width=\"85\" height=\"85\" \/><\/td>\n<td><strong> M\u00c1XIMO RENDIMIENTO EN A\u00d1OS <\/strong><br \/>\nSi desea un dispositivo EMS que est\u00e9 a la altura de los <strong> \u00faltimos desarrollos en tecnolog\u00eda EMS <\/strong> y en el que pueda confiar en su servicio durante a\u00f1os, Actiwave es la opci\u00f3n perfecta para usted.<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"alignleft wp-image-4179\" src=\"\/wp-content\/uploads\/2017\/06\/51-roi.png\" alt=\"\" width=\"85\" height=\"85\" \/><\/td>\n<td><strong> R\u00c1PIDA RENTABILIDAD DE LA INVERSI\u00d3N <\/strong><br \/>\nActiwave <strong> reducir\u00e1 significativamente sus inversiones comerciales <\/strong> al no tener que comprar dos dispositivos EMS, y tambi\u00e9n reducir\u00e1 sus costos operativos, <strong> mientras aumenta sus ingresos <\/strong> al abrir nuevas oportunidades comerciales con el Modo de entrenamiento en grupo y programa dual.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/ACTIWAVE-Hybrid-2Persons.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"maybegluetobottom margins section\"><div class=\"regular-container\"><div class=\"button-only story-section\"><div style=\"text-align: center; width: 100%;\"  class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"button solid\" href=\"\/es\/contact-us\/\">Obtener una cotizaci\u00f3n<\/a>\n\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"displaynoneimportant wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"accent-bg section testimonial-section\">\n\t<div class=\"regular-container\">\n\t\t<div class=\"testimonial-slider w-slider\" data-animation=\"slide\" data-autoplay=\"1\" data-delay=\"12000\" data-duration=\"500\" data-infinite=\"1\">\n\t\t\t<div class=\"w-slider-mask\">\n\t\t\t\t<div class=\"w-slide\">\n\t\t\t\t\t<div class=\"testimonial-wrapper\">\n\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Suspendisse varius enim in eros elementum tristique. Duis cursus, mi quis viverra ornare, eros dolor interdum nulla, ut commodo diam libero vitae erat. Aenean faucibus nibh et justo cursus id rutrum lorem imperdiet. Nunc ut sem vitae risus tristique posuere.<\/p>\n<p><!--img src=\"http:\/\/uploads.webflow.com\/58f0d3b1bf2d6363e82d4ee8\/5905e8c09086586eadd9a23d_markus-beispiel%402x.png\" width=\"60\" \/ --><\/p>\n<div class=\"flex-2-col\">\n<div>\n<div class=\"testimonial-name\">Markus Beispiel<\/div>\n<div class=\"testimonial-info\">Studio Owner, Berlin, Germany<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t<div class=\"w-slide\">\n\t\t\t\t\t<div class=\"testimonial-wrapper\">\n\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Suspendisse varius enim in eros elementum tristique. Duis cursus, mi quis viverra ornare, eros dolor interdum nulla, ut commodo diam libero vitae erat. Aenean faucibus nibh et justo cursus id rutrum lorem imperdiet. Nunc ut sem vitae risus tristique posuere.<\/p>\n<div class=\"flex-2-col\">\n<div class=\"testimonial-image-wrapper\"><!--img src=\"http:\/\/uploads.webflow.com\/58f0d3b1bf2d6363e82d4ee8\/5905e8c09086586eadd9a23d_markus-beispiel%402x.png\" width=\"60\" \/ --><\/div>\n<div>\n<div class=\"testimonial-name\">Markus Beispiel<\/div>\n<div class=\"testimonial-info\">Studio Owner, Berlin, Germany<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"testimonnial-slider-nav w-round w-slider-nav w-slider-nav-invert\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"threecolumn margins section dark\">\n    <div class=\"wide-container\">\n\t\t<h1 class=\"section-heading light\">ESPECIFICACIONES T\u00c9CNICAS<\/h1>\n        <div class=\"icon-card-section\">\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4654 size-full\" src=\"\/wp-content\/uploads\/2017\/06\/go-out-light-e1505293453730.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> Funci\u00f3n de salida <\/h4>\n<p>Con la ayuda de la funci\u00f3n Salir, los clientes ya no est\u00e1n restringidos a estar cerca del dispositivo EMS, lo que abre un mundo completamente nuevo de posibilidades de entrenamiento. Los ajustes preestablecidos se almacenan en el dispositivo Actiwear y se pueden utilizar fuera del alcance de la red inal\u00e1mbrica para disfrutar de total libertad en interiores o exteriores.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4273\" src=\"\/wp-content\/uploads\/2017\/06\/15IPSScreen.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>Pantalla t\u00e1ctil IPS de 15 &#8220;<\/h4>\n<p>Pantalla t\u00e1ctil grande y duradera, f\u00e1cil de usar, f\u00e1cil de aprender. La pantalla gr\u00e1fica proporciona un aspecto moderno y agradable a los usuarios.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4277\" src=\"\/wp-content\/uploads\/2017\/06\/small-footprint.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>130 x 40 cm<\/h4>\n<p>Dise\u00f1ado para la perfecci\u00f3n. Puede moverlo dentro de su estudio, planificar su espacio de entrenamiento en torno a \u00e9l, pero tambi\u00e9n puede llevarlo a sus clientes.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4281\" src=\"\/wp-content\/uploads\/2017\/06\/usb-hdmi.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Puertos USB y HDMI<\/h4>\n<p>Puerto USB para instalar las actualizaciones y el puerto HDMI para conectar su TELEVISOR o proyector para la m\u00e1xima comodidad de sus clientes.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4283\" src=\"\/wp-content\/uploads\/2017\/06\/online.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4> XBody en l\u00ednea <\/h4>\n<p>Conexi\u00f3n WiFi segura para administrar f\u00e1cilmente la informaci\u00f3n de entrenamiento con nuestro servicio XBody Online.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4656 size-full\" src=\"\/wp-content\/uploads\/2017\/06\/12-channels-light-e1505293570772.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> 12 canales de estimulaci\u00f3n <\/h4>\n<p>Los dispositivos Actiwave y Actiwear utilizan 12 canales de estimulaci\u00f3n para estimular los m\u00fasculos de todo el cuerpo. Las bandas para los hombros y las pantorrillas se pueden usar juntas como una extensi\u00f3n del traje normal, mientras que un canal opcional a\u00fan permite colocar un par adicional de electrodos.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4286\" src=\"\/wp-content\/uploads\/2017\/06\/batteries.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Actiwear: 4 bater\u00edas de iones de litio<\/h4>\n<p>Actiwear utiliza bater\u00edas de alta capacidad, que puede usar f\u00e1cilmente durante todo un d\u00eda sin recargarlas.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4289\" src=\"\/wp-content\/uploads\/2017\/06\/software-updates.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> Actualizaciones de software peri\u00f3dicas <\/h4>\n<p>Nuestro equipo de investigaci\u00f3n y desarrollo trabaja continuamente para ofrecer mejoras que hagan que el uso de nuestro dispositivo sea conveniente, nuestros softwares, funciones y servicios est\u00e9n actualizados y siempre al menos un paso por delante de la competencia.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4292\" src=\"\/wp-content\/uploads\/2017\/06\/easy-maintanance.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Mantenimiento sencillo<\/h4>\n<p>Actiwave est\u00e1 dise\u00f1ado para sobresalir y que el mantenimiento sea lo m\u00e1s sencillo posible. Todas las piezas de repuesto est\u00e1n continuamente disponibles en nuestro almac\u00e9n o con nuestros distribuidores locales.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<style>\n\t.multi-column-image-container img {\n\t\tmax-height: 250px;\n\t}\n<\/style>\n\n<div  class=\"products2   margins section\">\n\t<div class=\"wide-container\">\n\t\t<h2 class=\"section-heading\">Soportes<\/h2>\n\t\t<p class=\"paragraph section\">M\u00faltiples soportes son compatibles con XBody Actiwave, Newave y Newave Med.<\/p>\n\t<div class=\"multi-column-wrapper\">\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-1.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte Est\u00e1ndar<\/h4>\n\t\t\t\t<p><p>El soporte est\u00e1ndar <strong> se adapta a todos los entornos <\/strong>, pero su dise\u00f1o \u00fanico y ergon\u00f3mico lo hace destacar y no ocupar\u00e1 m\u00e1s de 2 m\u00b2 de su espacio. Debido a su peso ligero, puede transportarlo f\u00e1cilmente.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/stand_1.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte FlowR<\/h4>\n\t\t\t\t<p><p>El soporte FlowR <strong> hace que el entrenamiento grupal cableado sea f\u00e1cilmente posible <\/strong>, al m\u00e1s alto nivel. La instalaci\u00f3n de Newaves en el soporte FlowR te permitir\u00e1 entrenar a 3 clientes al mismo tiempo, pero tener 3 Actiwaves te dar\u00e1 la oportunidad de entrenar hasta 3 x 6 clientes.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-3.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte Port\u00e1til<\/h4>\n\t\t\t\t<p><p>El soporte port\u00e1til est\u00e1 siempre a mano, ya sea un entrenamiento personal solicitado en casa de un cliente, como durante un viaje o vacaciones. Es <strong> f\u00e1cil de transportar <\/strong> en una elegante maleta, por lo que el entrenador puede ofrecer un entrenamiento de calidad fuera del estudio.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-4.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte de pared<\/h4>\n\t\t\t\t<p><p>El soporte de pared es una combinaci\u00f3n perfecta de un <strong> accesorio de pared que ahorra espacio <\/strong> y una versi\u00f3n port\u00e1til. \u00daselo fijo en la pared de su estudio y h\u00e1galo m\u00f3vil con un simple movimiento si es necesario. La fuente de alimentaci\u00f3n est\u00e1 discretamente oculta para un dise\u00f1o minimalista. Tambi\u00e9n es ideal para yates y cruceros.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"accent-bg margins section xbody-twopost\">\n\t<div class=\"regular-container\">\n\t\t<div class=\"center story-section\">\n\t\t\t<h2 class=\"mb-50 section-heading\">VAMOS A PONERNOS EN CONTACTO<\/h2>\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t<div class=\"w-col w-col-6 w-col-small-9 w-col-tiny-11\">\n\t\t\t\t\t<div class=\"padded-holder\">\n\t\t\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/np_mail.png\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"intro paragraph\">\u00bfQUIERES SABER M\u00c1S SOBRE LOS DISPOSITIVOS DE ENTRENAMIENTO XBODY EMS?<\/p>\n\t\t\t\t\t\t<p class=\"paragraph\"><p>Cont\u00e1ctenos, responderemos sus preguntas y le daremos un presupuesto personalizado para sus necesidades comerciales.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"https:\/\/es.xbodyworld.com\/es\/contactenos\/\">Cont\u00e1ctenos<\/a>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"w-col w-col-6 w-col-small-9 w-col-tiny-11\">\n\t\t\t\t\t<div class=\"padded-holder\">\n\t\t\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/np_globe.png\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"intro paragraph\">\u00bfQUIERES CONVERTIRTE EN DISTRIBUIDOR DE DISPOSITIVOS XBODY EMS?<\/p>\n\t\t\t\t\t\t<p class=\"paragraph\"><p>\u00danase a la familia XBody y solicite derechos para distribuir productos XBody en su pa\u00eds.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"button\" href=\"https:\/\/es.xbodyworld.com\/es\/convertirse-en-distribuidor-xbody\/\">SOLICITAR DERECHOS DE DISTRIBUCI\u00d3N<\/a>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"EL H\u00cdBRIDO El primer dispositivo EMS h\u00edbrido del mundo que permite entrenar con y sin cable al mismo tiempo. Actiwave se dise\u00f1\u00f3 para adaptarse a cualquier necesidad de entrenamiento de EMS y a cualquier modelo de negocio, y ofrece oportunidades de ingresos \u00fanicas. Multiplique sus ingresos con sesiones de entrenamientos en grupo para hasta 6 [...]","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/1383"}],"collection":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/comments?post=1383"}],"version-history":[{"count":60,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/1383\/revisions"}],"predecessor-version":[{"id":37381,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/1383\/revisions\/37381"}],"wp:attachment":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/media?parent=1383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}