{"id":260,"date":"2017-05-30T11:31:27","date_gmt":"2017-05-30T11:31:27","guid":{"rendered":"http:\/\/xbodyworld.com\/?page_id=260"},"modified":"2021-01-04T19:09:37","modified_gmt":"2021-01-04T18:09:37","slug":"xbody-newave","status":"publish","type":"page","link":"https:\/\/es.xbodyworld.com\/es\/xbody-newave\/","title":{"rendered":"XBody Newave"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"headerpost first section\">\n\n\t<div class=\"slide w-slide no-bg post-262 post-debug-262\" style=\"transform: translateX(0px); opacity: 1;\">\n\t\t<div class=\"vertical-center-left wide-container\">\n\t\t\t<div class=\"content-wrapper-50\">\n\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4409 size-medium\" src=\"\/wp-content\/uploads\/2017\/05\/Newave-300x40.png\" alt=\"\" width=\"300\" height=\"40\" srcset=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Newave-300x40.png 300w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Newave-768x102.png 768w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Newave.png 904w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h1>ESTABLECIDO. EXITOSO. ECON\u00d3MICO.<\/h1>\n<p>Entrene a sus clientes con el dispositivo EMS establecido y galardonado que utilizan a diario m\u00e1s de mil estudios en todo el mundo. Con sus m\u00faltiples programas de entrenamiento cardiovascular y de fuerza integrados, la pantalla t\u00e1ctil f\u00e1cil de usar y los detalles cuidadosamente dise\u00f1ados, <strong> Newave representa el entrenamiento con cables en su mejor forma. <\/strong><\/p>\n<p><strong> Uno de los dispositivos EMS m\u00e1s vendidos en el mundo,<\/strong> Newave es la soluci\u00f3n perfecta para entrenamientos personales individuales con cable.<\/p>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"content-wrapper-50 full-height\">\n\t\t\t\t\t\t<img class=\"full-width-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/5-newave-3.png\" >\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"bottom-border section\"><div class=\"breadcrumbs-wrapper\"><a class=\"breadcrumbs-link\" href=\"https:\/\/es.xbodyworld.com\/es\" rel=\"nofollow\" >Home<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-267\">\n\t<div class=\"regular-container\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">BENEFICIOS DE NEWAVE<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Probado en todo el mundo: nuestro \u00e9xito de ventas durante muchos a\u00f1os<\/h3><p>Construido con materiales de la m\u00e1s alta calidad, dise\u00f1ado para resaltar todas las ventajas de la tecnolog\u00eda EMS con cable. XBody Newave fue el primer dispositivo EMS que combin\u00f3 belleza, ergonom\u00eda y eficiencia para liderar el mercado de EMS con cable y <strong> su \u00e9xito mundial es la prueba de su excelencia. <\/strong><\/p>\n<p>A lo largo de los a\u00f1os, se ha demostrado que Newave es uno de los dispositivos EMS m\u00e1s populares del mundo y <strong> actualmente se usa a diario en m\u00e1s de 2000 estudios en todo el mundo. <\/strong> Su dise\u00f1o moderno, pantalla t\u00e1ctil de f\u00e1cil uso, el software de entrenamiento actualizado y las actualizaciones continuas de funciones garantizan que Newave est\u00e9 aqu\u00ed para quedarse en los pr\u00f3ximos a\u00f1os.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id: Wq0Iv8BrtJA -->\t\t\t\t\t\t\t\t<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: Wq0Iv8BrtJA -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/Wq0Iv8BrtJA?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/wIMG_0498_rr.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Entrenamiento cableado en su mejor momento<\/h3>\n\t\t\t\t\t\t\t<p>El \u00e9xito de XBody Newave se debe en gran parte al hecho de que <strong> se acerca al entrenamiento EMS con cable tradicional desde un \u00e1ngulo diferente. <\/strong> Es f\u00e1cil de aprender, f\u00e1cil de mantener, ofrece una variedad de caracter\u00edsticas para ayudar a los entrenadores y se centra en ofrecer un entrenamiento EMS verdaderamente eficaz para los clientes.<\/p>\n<p>El <strong> software innovador que se actualiza peri\u00f3dicamente <\/strong> ofrece varios programas de entrenamiento en v\u00eddeo para diferentes objetivos de entrenamiento, funciones de entrenamientos f\u00e1cilmente personalizables, gesti\u00f3n de perfiles de clientes, estad\u00edsticas de entrenamientos, autenticaci\u00f3n de entrenadores y mucho m\u00e1s.<\/p>\n<p>Su cable flexible asegura que la conexi\u00f3n entre nuestro traje de entrenamiento profesional y el dispositivo sea perfecta para los clientes y la longitud del cable <strong> le permite realizar todo tipo de ejercicios, desde el fortalecimiento hasta el entrenamiento cardiovascular y el masaje relajante tambi\u00e9n<\/strong>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Profesional y econ\u00f3mico<\/h3><p>Los dispositivos XBody han sido dise\u00f1ados y <strong> desarrollados para proporcionar a los entrenadores y empresas un equipo profesional <\/strong> para que puedan ofrecer formaciones verdaderamente eficaces a sus clientes.<\/p>\n<p><strong> Newave ha demostrado su durabilidad y confiabilidad a lo largo de los a\u00f1os. <\/strong> Dise\u00f1ado y fabricado con materiales de la m\u00e1s alta calidad, Newave es uno de los dispositivos m\u00e1s f\u00e1ciles de mantener en el mercado, que es confiable durante a\u00f1os y <strong> ofrece una soluci\u00f3n muy rentable para cualquier empresa. <\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/52-proven-1.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-274 colored-bg gradient\">\n\t<div class=\"regular-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont light intro\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">La decisi\u00f3n establecida<\/h3><p>Newave ha cambiado por completo el mercado de EMS y se ha convertido en el punto de referencia de excelencia para el entrenamiento con cable a lo largo de los a\u00f1os. <strong> Ganador de m\u00faltiples premios en la industria de EMS, Newave es realmente una elecci\u00f3n en la que cualquiera puede confiar. <\/strong><\/p>\n<p>Su hermoso dise\u00f1o y su familiar pantalla t\u00e1ctil han demostrado que los dispositivos EMS pueden ser f\u00e1ciles de usar. Su amplia gama de funciones ha demostrado que <strong> mediante el uso de dispositivos avanzados, las empresas pueden tener a\u00fan m\u00e1s \u00e9xito. <\/strong><\/p>\n<p>Y su \u00e9xito y fiabilidad en todo el mundo durante a\u00f1os han demostrado que <strong> puede soportar incluso el uso diario m\u00e1s activo en cualquier gimnasio. <\/strong><\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"https:\/\/shop.xbodyworld.es\/es\/producto\/newave-package\/\">Comprar ahora<\/a>\n\t\t\t<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-64\" src=\"\/wp-content\/uploads\/2017\/05\/5905ee5e0737332a98b116c5_FIBO_Innocation_Award_Winner@2x.png\" alt=\"\" width=\"103\" height=\"103\" srcset=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/5905ee5e0737332a98b116c5_FIBO_Innocation_Award_Winner@2x.png 206w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/5905ee5e0737332a98b116c5_FIBO_Innocation_Award_Winner@2x-150x150.png 150w\" sizes=\"(max-width: 103px) 100vw, 103px\" \/><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/52-established-e1504184745511.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins no-margin-bottom noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h2 style=\"text-align: center\">CARACTER\u00cdSTICAS NEWAVE<\/h2>\n<p style=\"text-align: center\">Confiado durante muchos a\u00f1os, Newave ha demostrado su alta calidad y eficacia en todo el mundo.<\/p>\n<\/div>\n\t\t\t\t\t<\/div><div class=\"threecolumn margins section light notopspace\">\n    <div class=\"wide-container\">\n        <div class=\"icon-card-section\">\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4323 aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/wired.png\" alt=\"\" width=\"100\" height=\"100\" srcset=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/wired.png 203w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/wired-150x150.png 150w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/p>\n<h4>Entrenamiento de EMS con cable<\/h4>\n<p>Newave ha demostrado su eficacia en el m\u00e9todo de entrenamiento EMS tradicional y cableado en todo el mundo.<strong> El dispositivo y su software de entrenamiento est\u00e1n conectados con el traje de entrenamiento<\/strong> y env\u00edan las se\u00f1ales a todos los lugares correctos durante el entrenamiento. Newave viene con las conexiones de cable magn\u00e9tico m\u00e1s recientes para que los entrenamientos puedan comenzar r\u00e1pidamente y f\u00e1cilmente.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4332 aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/video-trainer.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<p><strong>Programas de Fuerza, Cardio y Relajaci\u00f3n<\/strong><\/p>\n<p>Entrena a tus clientes de acuerdo a sus propios objetivos y seguir\u00e1n volviendo a ti para lograrlo. <strong>Configure entrenamientos complejos con los programas de entrenamiento integrados o cree entrenamientos personalizados por su cuenta<\/strong>. El dispositivo proporciona programas dedicados de entrenamiento muscular, cardiovascular y de relajaci\u00f3n junto con un programa de entrenamiento manual totalmente personalizable<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4332 aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/video-trainer.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4><strong>Programa Entrenador Virtual<\/strong><\/h4>\n<p>El Programa de Entrenador Virtual integrado asegura que los entrenamientos est\u00e9n optimizados y los ejercicios se implementen de la manera correcta, <strong>sin la necesidad que el entrenador haga los ejercicios con los clientes<\/strong>. El uso del Programa Entrenador Virtual permite a los entrenadores centrarse en la posici\u00f3n, postura y rendimiento de los clientes para maximizar los resultados.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4336 aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/suti-cable-2.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>Conexi\u00f3n de cable magn\u00e9tico<\/h4>\n<p>Nuestros nuevos cables cuentan con una conexi\u00f3n magn\u00e9tica entre el traje de entrenamiento profesional y el dispositivo, lo que hace que el montaje sea a\u00fan m\u00e1s conveniente, sin problemas y m\u00e1s r\u00e1pido. <strong>Esta conexi\u00f3n magn\u00e9tica es r\u00e1pida, fiable y la transferencia de impulsos est\u00e1 optimizada.<\/strong><\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4339 aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/top-performer.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4><strong> Mejor desempe\u00f1o en EMS<br \/>\n<\/strong><\/h4>\n<p style=\"text-align: left;\">Newave se cre\u00f3 para maximizar la eficacia del entrenamiento EMS. Con sus conexiones de cable magn\u00e9tico m\u00e1s recientes, programas de entrenamiento integrados y probados, amplias opciones de personalizaci\u00f3n y al operar dentro del rango m\u00e1s eficiente de frecuencia EMS, <strong> puede estar seguro de que sus clientes obtendr\u00e1n los resultados a los que se inscribieron. <\/strong><\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header\"><\/h4>\n                    <p class=\"paragraph light\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"wp-image-4344 aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/custom-training.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Sesiones de entrenamiento personalizado<\/h4>\n<p>El XBody Newave ofrece un mont\u00f3n de posibilidades para personalizar los entrenamientos personales de acuerdo con el nivel de fitness de su cliente. <strong>Ajuste la frecuencia, la intensidad o cualquier otro par\u00e1metro<\/strong> con la pantalla t\u00e1ctil f\u00e1cil de usar y el software f\u00e1cil de usar para crear sesiones de entrenamiento personalizadas.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/div><div class=\"maybegluetobottom margins section\"><div class=\"regular-container\"><div class=\"button-only story-section\"><div style=\"text-align: center; width: 100%;\"  class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"https:\/\/shop.xbodyworld.es\">COMPRAR AHORA<\/a>\n\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-286 accent-bg\">\n\t<div class=\"wide-container\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">ABRE TU ESTUDIO DE ENTRENAMIENTO EMS CON XBODY NEWAVE<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/FITEXPRESS-DK-e1504184993184.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Entrenamiento cableado en su mejor momento.<\/h3>\n\t\t\t\t\t\t\t<table class=\"nonmax csptable\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" class=\"alignnone wp-image-5728 size-full\" src=\"\/wp-content\/uploads\/2017\/05\/personal-vip-corporate-training-model-icon-dark-72.png\" alt=\"\" width=\"72\" height=\"72\" \/><\/td>\n<td><a href=\"\/es\/personal-vip-corporate-concepts\/\"><strong>Soluciones Personales, VIP, Corporativo<\/strong><\/a><br \/>\nNewave es un excelente modelo para iniciar entrenamientos personales, entrenamientos VIP en el hogar o entrenamientos corporativos. Como <strong>el dispositivo inicial perfecto, viene con una amplia gama de caracter\u00edsticas<\/strong> que ser\u00e1n \u00fatiles si usted est\u00e1 planeando cambiar el mundo un cliente a la vez.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><a href=\"\/es\/microstudio-model\/\"><strong> MODELO MICROSTUDIO<br \/>\n<\/strong><\/a>Unirse a los m\u00e1s de mil estudios que conf\u00edan en Newave en todo el mundo cada d\u00eda. Tambi\u00e9n puede ser la soluci\u00f3n correcta si<strong> planea iniciar un Microstudio y desea centrarse en los entrenamientos VIP y personales.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Obtenga m\u00e1s informaci\u00f3n sobre nuestros <a href=\"\/es\/proven-business-models-in-ems\/\">modelos de negocio.<\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div>\n<div  class=\"margins section xbody-changingside post-291  nobottomspace\">\n\t<div class=\"wide-container nobottomspace\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">VENTAJAS COMERCIALES DE XBODY NEWAVE<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<table class=\"nonmax csptable\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" class=\"wp-image-4661 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/advanced-wired-e1505294112290.png\" alt=\"\" width=\"42\" height=\"85\" \/><\/td>\n<td><strong>DISPOSITIVO AVANZADO DE EMS CON CABLE<\/strong><br \/>\nNewave representa todos los \u00faltimos desarrollos en tecnolog\u00eda EMS cableada y eso significa una amplia gama de caracter\u00edsticas para optimizar los procesos y la participaci\u00f3n del entrenador,<strong> reducir el tiempo de configuraci\u00f3n del entrenamiento y los costos operativos.<\/strong><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"wp-image-4366 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/52-proven.png\" alt=\"\" width=\"84\" height=\"85\" srcset=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/52-proven.png 266w, https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/52-proven-150x150.png 150w\" sizes=\"(max-width: 84px) 100vw, 84px\" \/><\/td>\n<td><strong>SELECCI\u00d3N DE CONFIANZA, RENDIMIENTO CONFIABLE<\/strong><br \/>\nNada es m\u00e1s caro en un negocio que riesgos y consecuencias imprevistos. Es importante elegir un dispositivo EMS como Newave que haya<strong> demostrado su eficacia, seguridad y fiabilidad a largo plazo en el mercado.<\/strong><\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"wp-image-4365 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/52-standout.png\" alt=\"\" width=\"84\" height=\"82\" \/><\/td>\n<td><strong>DESTACARSE DE LA COMPETENCIA<\/strong><br \/>\nNewave ha sido dise\u00f1ado para profesionales que quieren ofrecer a los clientes <strong>la mejor experiencia posible y convertirlos en clientes leales y que regresan.<\/strong> Los entrenamientos personalizados, los ejercicios de v\u00eddeo integrados, los programas de entrenamiento personalizados, la configuraci\u00f3n de entrenamiento sin interrupciones y su dise\u00f1o elegante ayudan a que la experiencia del entrenamiento de EMS de sus clientes se destaque de la competencia.<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" class=\"wp-image-4662 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/05\/effective-economical-e1505294182529.png\" alt=\"\" width=\"85\" height=\"63\" \/><\/td>\n<td><strong>EFICAZ Y ECON\u00d3MICO<br \/>\n<\/strong>Newave ha demostrado su fiabilidad a lo largo de los a\u00f1os, incluso en el uso diario m\u00e1s activo. Su dise\u00f1o duradero y su alta calidad hacen que sea<strong> f\u00e1cil de mantener y mantener los costes de mantenimiento bajos, lo que puede significar un ahorro de cientos de euros cada mes.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/51-mark-keller.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"maybegluetobottom margins section\"><div class=\"regular-container\"><div class=\"button-only story-section\"><div style=\"text-align: center; width: 100%;\"  class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"button solid\" href=\"https:\/\/shop.xbodyworld.es\/es\/categoria-producto\/complete-packages\/\">Comprar ahora<\/a>\n\t\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"threecolumn margins section dark\">\n    <div class=\"wide-container\">\n\t\t<h1 class=\"section-heading light\">ESPECIFICACIONES T\u00c9CNICAS<\/h1>\n        <div class=\"icon-card-section\">\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4666 size-full\" src=\"\/wp-content\/uploads\/2017\/06\/easy-to-manage-light-e1505295627123.png\" alt=\"\" width=\"100\" height=\"101\" \/><\/p>\n<h4>Entrenamiento f\u00e1cil de administrar<\/h4>\n<p>Todas las funciones relacionadas con el entrenamiento est\u00e1n disponibles en una \u00fanica ventana de entrenamiento. Las intensidades de estimulaci\u00f3n se pueden ajustar con la ayuda de reguladores de 10 canales para todo el cuerpo. La se\u00f1al de estimulaci\u00f3n se puede parametrizar para adaptarse a diversas necesidades. La capacidad de respuesta del sistema de estimulaci\u00f3n garantiza un entrenamiento seguro y altamente efectivo.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4296\" src=\"\/wp-content\/uploads\/2017\/06\/10touch-screen.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Pantalla t\u00e1ctil de 10 &#8220;<\/h4>\n<p>Pantalla t\u00e1ctil duradera y del tama\u00f1o de una tableta, f\u00e1cil de usar, f\u00e1cil de aprender. La pantalla gr\u00e1fica proporciona un aspecto moderno y agradable a los usuarios.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4277\" src=\"\/wp-content\/uploads\/2017\/06\/small-footprint.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>Tama\u00f1o conveniente<\/h4>\n<p>130 cm (~ 4,2 pies) de alto, 40 cm (~ 1,3 pies) de ancho, f\u00e1cil de mover por el estudio, planifique su espacio de entrenamiento a su alrededor, pero tambi\u00e9n puede llevarlo a sus clientes.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4299\" src=\"\/wp-content\/uploads\/2017\/06\/lightweight.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> Ligero <\/h4>\n<p>Con solo 17 kg (~ 37 lb), incluido el soporte est\u00e1ndar, puede transportarlo f\u00e1cilmente y el env\u00edo tambi\u00e9n tiene un precio razonable.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4301\" src=\"\/wp-content\/uploads\/2017\/06\/multi-language.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> Varios idiomas <\/h4>\n<p>Los textos mostrados y el teclado virtual se pueden personalizar para admitir numerosos idiomas. Hay traducciones disponibles para la mayor\u00eda de los idiomas europeos, americanos y asi\u00e1ticos.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4303\" src=\"\/wp-content\/uploads\/2017\/06\/advanced-stimulation.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4> Estimulaci\u00f3n avanzada <\/h4>\n<p>El dispositivo utiliza una onda cuadrada bipolar sim\u00e9trica para la estimulaci\u00f3n. La frecuencia de la se\u00f1al se puede configurar entre 1-100 Hz, que es el rango operativo m\u00e1s eficiente de EMS. El Newave se puede utilizar en modos de estimulaci\u00f3n continua y en r\u00e1fagas.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4289\" src=\"\/wp-content\/uploads\/2017\/06\/software-updates.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>Actualizaciones regulares de software<\/h4>\n<p>Nuestro equipo de investigaci\u00f3n y desarrollo trabaja continuamente en la entrega de mejoras que hacen que el uso de nuestro dispositivo sea conveniente, nuestros softwares, caracter\u00edsticas y servicios actualizados, y siempre al menos un paso por delante de cualquier competidor.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4292\" src=\"\/wp-content\/uploads\/2017\/06\/easy-maintanance.png\" alt=\"\" width=\"100\" height=\"100\" \/><\/p>\n<h4>F\u00e1cil mantenimiento<\/h4>\n<p>Nuestros dispositivos est\u00e1n dise\u00f1ados para sobresalir en hacer que el mantenimiento sea lo m\u00e1s sencillo posible. Todas las piezas de repuesto est\u00e1n continuamente disponibles en nuestro almac\u00e9n o en nuestros distribuidores locales.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t            <div class=\"icon-card\">\n                <div class=\"icon-container\" style=\"\" >\n\t\t\t\t\t<img src=\"\" >\n\t\t\t\t<\/div>\n                <div class=\"text-container\" style=\"\" >\n                    <h4 class=\"icon-card-header light\"><\/h4>\n                    <p class=\"paragraph dark\">\n\t\t\t\t\t\t<p><img loading=\"lazy\" class=\"alignnone wp-image-4307\" src=\"\/wp-content\/uploads\/2017\/05\/USB.png\" alt=\"\" width=\"99\" height=\"100\" \/><\/p>\n<h4>Puerto USB<\/h4>\n<p>Con la ayuda del puerto USB, el Newave es capaz de proporcionar funcionalidades de importaci\u00f3n y exportaci\u00f3n para copias de seguridad y estad\u00edsticas de dispositivos. El software tambi\u00e9n se puede actualizar f\u00e1cilmente descargando nuestros archivos de actualizaci\u00f3n a una memoria USB y conect\u00e1ndolo a la m\u00e1quina.<\/p>\n\t\t\t\t\t<\/p>\n                <\/div>\n            <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<style>\n\t.multi-column-image-container img {\n\t\tmax-height: 250px;\n\t}\n<\/style>\n\n<div  class=\"products2   margins section\">\n\t<div class=\"wide-container\">\n\t\t<h2 class=\"section-heading\">Soportes<\/h2>\n\t\t<p class=\"paragraph section\">M\u00faltiples soportes son compatibles con XBody Actiwave, Newave y Newave Med.<\/p>\n\t<div class=\"multi-column-wrapper\">\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-1.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte Est\u00e1ndar<\/h4>\n\t\t\t\t<p><p>El soporte est\u00e1ndar <strong> se adapta a todos los entornos <\/strong>, pero su dise\u00f1o \u00fanico y ergon\u00f3mico lo hace destacar y no ocupar\u00e1 m\u00e1s de 2 m\u00b2 de su espacio. Debido a su peso ligero, puede transportarlo f\u00e1cilmente.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/stand_1.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte FlowR<\/h4>\n\t\t\t\t<p><p>El soporte FlowR <strong> hace que el entrenamiento grupal cableado sea f\u00e1cilmente posible <\/strong>, al m\u00e1s alto nivel. La instalaci\u00f3n de Newaves en el soporte FlowR te permitir\u00e1 entrenar a 3 clientes al mismo tiempo, pero tener 3 Actiwaves te dar\u00e1 la oportunidad de entrenar hasta 3 x 6 clientes.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-3.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte Port\u00e1til<\/h4>\n\t\t\t\t<p><p>El soporte port\u00e1til est\u00e1 siempre a mano, ya sea un entrenamiento personal solicitado en casa de un cliente, como durante un viaje o vacaciones. Es <strong> f\u00e1cil de transportar <\/strong> en una elegante maleta, por lo que el entrenador puede ofrecer un entrenamiento de calidad fuera del estudio.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"multi-column\">\n\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/stands-4.png\">\n\t\t\t<\/div>\n\t\t\t<div class=\"multi-colum-text-container posrelative\" >\n\t\t\t\t<h4>Soporte de pared<\/h4>\n\t\t\t\t<p><p>El soporte de pared es una combinaci\u00f3n perfecta de un <strong> accesorio de pared que ahorra espacio <\/strong> y una versi\u00f3n port\u00e1til. \u00daselo fijo en la pared de su estudio y h\u00e1galo m\u00f3vil con un simple movimiento si es necesario. La fuente de alimentaci\u00f3n est\u00e1 discretamente oculta para un dise\u00f1o minimalista. Tambi\u00e9n es ideal para yates y cruceros.<\/p>\n<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f36370-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/260#wpcf7-f36370-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/260#wpcf7-f36370-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"36370\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f36370-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:36370,&quot;conditions&quot;:[{&quot;then_field&quot;:&quot;-1&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;country&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;United State&quot;}]},{&quot;then_field&quot;:&quot;-1&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;-1&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;&quot;}]}],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<h1 style=\"text-align:center\">OBTENER UNA COTIZACI\u00d3N<\/h1>\n<div class=\"xbody-contactform\">\n<p><label> <span class=\"ml20\"> Correo electr\u00f3nico <\/span><small>(Campo requerido)<\/small><br \/>\n<span class=\"wpcf7-form-control-wrap email\"><input type=\"email\" name=\"email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><\/label><\/p>\n<p><label> <span class=\"ml20\">Nombre <\/span><small>(Campo requerido)<\/small><br \/>\n  <span class=\"wpcf7-form-control-wrap firstname\"><input type=\"text\" name=\"firstname\" value=\"\" size=\"40\" maxlength=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><span id=\"wpcf7-6a04ed9d2462d-wrapper\" class=\"wpcf7-form-control-wrap Firstname2-wrap\" ><label for=\"wpcf7-6a04ed9d2462d-field\" class=\"hp-message\">Por favor, deja este campo vac\u00edo.<\/label><input id=\"wpcf7-6a04ed9d2462d-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"Firstname2\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><\/p>\n<p><label> <span class=\"ml20\">Apellido <\/span><small>(Campo requerido)<\/small><br \/>\n  <span class=\"wpcf7-form-control-wrap lastname\"><input type=\"text\" name=\"lastname\" value=\"\" size=\"40\" maxlength=\"80\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> <span class=\"ml20\">Pa\u00eds de inter\u00e9s <\/span><small>(Campo requerido)<\/small><br \/>\n   <span class=\"wpcf7-form-control-wrap country\"><input type=\"text\" name=\"country\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-countrytext wpcf7-validates-as-required\" id=\"country\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label><span class=\"ml20\">Su n\u00famero de tel\u00e9fono de contacto <\/span><small>(Campo opcional)<\/small><br \/>\n<span class=\"wpcf7-form-control-wrap telnum\"><input type=\"text\" name=\"telnum\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-phonetext\" id=\"telnum\" aria-invalid=\"false\" \/><\/span><\/label>    <\/p>\n<p><label> <span class=\"ml20\">Mensaje <\/span><small>(Campo requerido)<\/small><br \/>\n     <span class=\"wpcf7-form-control-wrap message\"><textarea name=\"message\" cols=\"40\" rows=\"5\" maxlength=\"1000\" minlength=\"20\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Si\u00e9ntase libre de escribir aqu\u00ed si tiene alguna pregunta o comentario espec\u00edfico que desea que sepamos\"><\/textarea><\/span><span class=\"wpcf7-character-count up\" data-target-name=\"message\" data-starting-value=\"0\" data-current-value=\"0\" data-maximum-value=\"1000\" data-minimum-value=\"20\">0<\/span>\/1000<br \/>\n<\/label><\/p>\n<p><label><span class=\"wpcf7-form-control-wrap privacy_policy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy_policy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\"><span class=\"replaceme-844\">Acepto la <a href=\"\/es\/cookie-and-privacy-policy\/\" >pol\u00edtica de privacidad<\/a><\/span><\/span><\/label><\/span><\/span><\/span><\/label><\/p>\n<input type=\"hidden\" name=\"LeadSource\" value=\"Website-Medical-Spain\" class=\"wpcf7-form-control wpcf7-hidden\" \/>\n<\/div>\n<div style=\"text-align: center\">\n<input type=\"submit\" value=\"ENVIAR\" class=\"wpcf7-form-control wpcf7-submit button large green\" \/><br \/>\n<small>\u00a1Nuestros colegas se pondr\u00e1n en contacto con usted en dos d\u00edas h\u00e1biles!<\/small><\/div>\n<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"23\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"ESTABLECIDO. EXITOSO. ECON\u00d3MICO. Entrene a sus clientes con el dispositivo EMS establecido y galardonado que utilizan a diario m\u00e1s de mil estudios en todo el mundo. Con sus m\u00faltiples programas de entrenamiento cardiovascular y de fuerza integrados, la pantalla t\u00e1ctil f\u00e1cil de usar y los detalles cuidadosamente dise\u00f1ados, Newave representa el entrenamiento con cables en [...]","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/260"}],"collection":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/comments?post=260"}],"version-history":[{"count":61,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/260\/revisions"}],"predecessor-version":[{"id":37382,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/260\/revisions\/37382"}],"wp:attachment":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/media?parent=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}