{"id":397,"date":"2017-05-31T09:26:56","date_gmt":"2017-05-31T09:26:56","guid":{"rendered":"http:\/\/xbodyworld.com\/?page_id=397"},"modified":"2021-01-04T18:58:47","modified_gmt":"2021-01-04T17:58:47","slug":"la-ventaja-xbody","status":"publish","type":"page","link":"https:\/\/es.xbodyworld.com\/es\/la-ventaja-xbody\/","title":{"rendered":"La Ventaja XBody"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"bgwhitening wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<style>\n\t.slide.post-399,\n\t.slide.post-debug-399 {\n\t\tbackground-position-x: 100%;\n\t\tbackground-position-y: 100%;\n\t\tbackground-size: cover;\n\t\tbackground-repeat: no-repeat;\n\t\tbackground-attachment: initial;\n\t\tbackground-origin: initial;\n\t\tbackground-clip: initial;\n\t\tbackground-color: initial;\n\t\tbackground-image: url(\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/xbody-advangate-1.jpg\");\n\t\t\t}\n\t\n<\/style>\n\n\n<div class=\"headerpost first section\">\n\n\t<div class=\"slide w-slide  post-399 post-debug-399\" style=\"transform: translateX(0px); opacity: 1;\">\n\t\t<div class=\"vertical-center-left wide-container\">\n\t\t\t<div class=\"content-wrapper-50\">\n\t\t\t\t<h1>\u00bfPOR QU\u00c9 XBODY?<\/h1>\n<p>La misi\u00f3n de XBody es proporcionar siempre a sus socios comerciales conceptos innovadores, \u00fanicos, eficientes, vers\u00e1tiles y rentables en el negocio de EMS.<\/p>\n<p><strong> No solo vendemos equipos, sino que tambi\u00e9n brindamos asistencia comercial y conocimientos t\u00e9cnicos completos para ayudarle a tener \u00e9xito. <\/strong><\/p>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"content-wrapper-50 full-height\">\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"bottom-border section\"><div class=\"breadcrumbs-wrapper\"><a class=\"breadcrumbs-link\" href=\"https:\/\/es.xbodyworld.com\/es\" rel=\"nofollow\" >Home<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-404\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/XBody-Logo-Flat-RGB-LR-500x116.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">SIEMPRE UN PASO ADELANTE<\/h3>\n\t\t\t\t\t\t\t<p><strong> XBody &#8230; La experiencia de entrenamiento profesional<br \/>\n<\/strong><br \/>\nLos dispositivos XBody han sido dise\u00f1ados y desarrollados para proporcionar a los entrenadores y empresas una <strong> herramienta profesional <\/strong> para poder ofrecer servicios de alta calidad a los clientes. Nuestros dispositivos no son simplemente tabletas ni tampoco dispositivos econ\u00f3micos de fitness para el hogar. Son herramientas duraderas y confiables con las que puede administrar un negocio. Est\u00e1n dise\u00f1ados por ingenieros calificados y fabricados con tecnolog\u00eda de punta utilizando \u00fanicamente <strong> materiales de la m\u00e1s alta calidad <\/strong> en nuestras propias instalaciones de producci\u00f3n.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<style>\n\t.xbody-changingside.post-767 {\n\t\tbackground: initial;\n\t\tbackground-image: url(\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/31-leading.jpg\");\n\t\tbackground-position: 50% 50%;\n\t\tbackground-size: cover;\n\t\tbackground-repeat: no-repeat;\n\t\t\t}\n\t\n<\/style>\n\n\n<div  class=\"margins section xbody-changingside post-767 no-bg\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">LIDERANDO EL CAMINO<\/h3>\n\t\t\t\t\t\t\t<p><strong>\u00bfQU\u00c9 HACE QUE LOS DISPOSITIVOS EMS DE XBODY SON TAN \u00daNICOS?<\/strong><br \/>\nNos esforzamos por desarrollar el mercado, crear tendencias, estar a la vanguardia, pero al mismo tiempo ofrecemos soluciones para las necesidades existentes del mercado y, por supuesto, para apoyar a nuestros socios y ayudarlos a hacer crecer sus propios negocios tambi\u00e9n.<\/p>\n<p>XBody se fund\u00f3 en 2010 y ha ido creciendo desde entonces. Hoy en d\u00eda, es uno de los mayores actores mundiales del mercado, <strong> brinda valor y la m\u00e1s alta calidad en todos los aspectos<\/strong>.<\/p>\n<p><strong> Desde su fundaci\u00f3n, XBody <\/strong> <strong> ha ganado varios premios en todo el mundo: <\/strong><\/p>\n<ul>\n<li>Premio FIBO a la Innovaci\u00f3n: Mejor Interior y Dise\u00f1o<\/li>\n<li>Premio Pegazus de inversores empresariales, Bisnode y Dentons: Mejor empresa en crecimiento<\/li>\n<li>Premio Deporte y Rusia: Mejor proyecto y producto innovador<\/li>\n<li>Medallista de oro en la Poznan Fitness Expo<\/li>\n<li>Ganador del premio Transdanubian Innovation Award<\/li>\n<li>Medallista de bronce en el TOP 100 empresas manufactureras del sector PYME<\/li>\n<li>Varios otros premios regionales<\/li>\n<li>Certificado AAA de Bisnode Creditworthy confiable y de buena reputaci\u00f3n<\/li>\n<\/ul>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" class=\"wp-image-3816 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/fibo-136x159.png\" alt=\"\" width=\"136\" height=\"159\" \/><\/td>\n<td><img loading=\"lazy\" class=\"wp-image-3817 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/poznan-136x159.png\" alt=\"\" width=\"136\" height=\"159\" \/><\/td>\n<td><img loading=\"lazy\" class=\"wp-image-3915 size-full aligncenter\" src=\"\/wp-content\/uploads\/2017\/06\/sport-and-russia-136x159.png\" alt=\"\" width=\"136\" height=\"159\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><strong>Innovaci\u00f3n FIBO<br \/>\n<\/strong><strong>Ganador del premio<br \/>\n<\/strong><\/td>\n<td style=\"text-align: center;\">Ganador de la medalla de oro<\/td>\n<td style=\"text-align: center;\"><strong>Mejor innovador<br \/>\nProyecto y producto<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-409\">\n\t<div class=\"wide-container\">\n\t\t\t\t\t<h1 class=\"mb-50 section-heading\">HECHO EN EUROPA<\/h1>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">CREAMOS NUESTROS DISPOSITIVOS EN NUESTRA PROPIA F\u00c1BRICA<\/h3><p>XBody tiene su propio <strong> equipo de desarrollo interno e instalaciones de fabricaci\u00f3n <\/strong>, que son componentes clave para nuestro \u00e9xito en el desarrollo continuo y las mejoras en los aspectos de hardware y software.<\/p>\n<p>Nuestro proceso de fabricaci\u00f3n est\u00e1 reforzado por una <strong> cadena de suministro controlada <\/strong> que otorga la m\u00e1xima calidad.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id: eItTVBo3EEk -->\t\t\t\t\t\t\t\t<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: eItTVBo3EEk -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/eItTVBo3EEk?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Screenshot_2-440x276.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">GESTI\u00d3N DE LA CALIDAD Y CERTIFICACIONES ISO<\/h3>\n\t\t\t\t\t\t\t<p>XBody ha obtenido los certificados <strong> ISO 13485: 2012 <\/strong>, <strong> 93\/42 EEC Compliance <\/strong> y <strong> EN ISO 9001: 2015 <\/strong>; y tambi\u00e9n ha implementado un <strong> Sistema de gesti\u00f3n de calidad <\/strong> interno para asegurar que los dispositivos y los servicios relacionados cumplen con los requisitos de la m\u00e1s alta calidad.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" class=\"alignnone wp-image-4073\" src=\"\/wp-content\/uploads\/2017\/06\/TUV_Rheinland_XBody_certification-300x111.png\" alt=\"\" width=\"200\" height=\"74\" \/><\/td>\n<td style=\"text-align: center;\">\u00a0<img loading=\"lazy\" class=\"alignnone wp-image-4204\" src=\"\/wp-content\/uploads\/2017\/06\/X-Body-ango-9001-300x184.jpg\" alt=\"\" width=\"121\" height=\"74\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><strong><br \/>\nT\u00dcV Rheinland Certified<\/strong><\/td>\n<td style=\"text-align: center;\"><strong><br \/>\nEN ISO 9001:2015<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">EQUIPO INTERNO DE INVESTIGACI\u00d3N Y DESARROLLO<\/h3><p>Nuestro <strong> equipo de investigaci\u00f3n y desarrollo <\/strong> trabaja continuamente para ofrecer mejoras que hagan que el uso de nuestro dispositivo sea conveniente, nuestros softwares, funciones y servicios est\u00e9n actualizados y siempre al menos un paso <strong> por delante de nuestro competidores <\/strong>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/31-one-step-ahead.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  class=\"margins section xbody-changingside post-828 colored-bg gradient minimalspace\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">DISE\u00d1O INTELIGENTE, ELEGANTE Y HERMOSO<\/h3><p>El <strong> dise\u00f1o moderno, <\/strong> <strong> sofisticado <\/strong> y la pantalla multit\u00e1ctil de XBody har\u00e1n que cualquier estudio parezca <strong> de alta tecnolog\u00eda e innovador<\/strong>. Nuestros conceptos de dise\u00f1o de estudio listos para usar ayudan a\u00fan m\u00e1s a crear un entorno atractivo.<\/p>\n<p>Obtenga m\u00e1s informaci\u00f3n sobre los dispositivos XBody y sus funciones para <strong> descubrir por qu\u00e9 son tan populares y \u00fanicos <\/strong> en el mercado de EMS.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"\/es\/xbody-products-ems-training-devices\/\">DISPOSITIVOS EMS &gt;<\/a>\n\t\t\t<\/div>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/51-actiwave-champion-big-e1504824355116.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins no-margin-bottom noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h2 class=\"mb-50 section-heading\" style=\"text-align: center;\">NOS OCUPAMOS DE SU \u00c9XITO<\/h2>\n<p style=\"text-align: center;\">\n<\/div>\n\t\t\t\t\t<\/div>\n<div  class=\"margins section xbody-changingside post-422  notopspace\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/31-ems-trainer-institute.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Entrenamiento profesional y educaci\u00f3n en tecnolog\u00eda EMS y mejores pr\u00e1cticas.<\/h3>\n\t\t\t\t\t\t\t<p>Al trabajar con los clientes a diario, los entrenadores son una parte esencial e importante del \u00e9xito de XBody. Es por eso que fundamos nuestro<strong> Instituto de entrenadores EMS <\/strong> \u00fanico, donde los entrenadores aprenden no solo los conceptos b\u00e1sicos y el uso de nuestros dispositivos, sino tambi\u00e9n a supervisar y motivar a los clientes de la manera adecuada, y a trabajar seg\u00fan las pautas y reglas para obtener los m\u00e1ximos resultados y la seguridad.<\/p>\n<p>Nuestros programas no solo forman instructores calificados, sino que tambi\u00e9n brindan <strong> habilidades de desarrollo comercial <\/strong> para ayudar a su personal a comprender los aspectos comerciales del concepto de EMS.<\/p>\n<p><strong> Puede maximizar sus resultados y su facturaci\u00f3n con XBody. <\/strong><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Red mundial de soporte y servicio<\/h3><p>Estamos orgullosos de ofrecer a nuestros socios <strong> garant\u00edas globales <\/strong> y una excelente y \u00fanica <strong>red de servicio completa <\/strong> a nivel mundial y local.<\/p>\n<p>Nuestro <strong> Portal de socios <\/strong> contiene toda la informaci\u00f3n y actualizaciones relacionadas con el funcionamiento y la configuraci\u00f3n, y est\u00e1 disponible en todo momento.<\/p>\n<p>Tambi\u00e9n nos destacamos por la velocidad de la comunicaci\u00f3n personal, todos los requisitos de asistencia se responden en un plazo de 2 d\u00edas h\u00e1biles y nuestro servicio de asistencia est\u00e1 <strong> disponible en todo el mundo<\/strong>.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Screenshot_1-440x276.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Screenshot_4-440x276.jpg\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3 class=\"story-header\">Entrega confiable y r\u00e1pida para que siempre reciba su pedido a tiempo<\/h3>\n\t\t\t\t\t\t\t<p>Hemos implementado el <strong> SAP Business Management System <\/strong> para servir a nuestros socios de la manera m\u00e1s eficiente y en un flujo optimizado. Todos los pedidos se procesan el mismo d\u00eda de env\u00edo, <strong> env\u00edo flexible y r\u00e1pido <\/strong> se proporciona desde nuestro stock extendido.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div  style=\"background: #343e48;\" class=\"margins section xbody-changingside post-431 colored-bg minimalspace\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont dark\">\n\t\t\t\t\t\t\t<h3 class=\"story-header dark\">Brindamos soporte empresarial y de marketing a nuestros socios<\/h3><p><span style=\"color: #ffffff;\">No solo vendemos dispositivos, sino que ayudamos a nuestros socios con planes comerciales reales, c\u00e1lculos de retorno de la inversi\u00f3n, mejores pr\u00e1cticas y <strong> valiosos consejos y recomendaciones <\/strong> sobre c\u00f3mo administrar un negocio de EMS. <\/span><\/p>\n<p><span style=\"color: #ffffff;\"> Nuestro portal de socios f\u00e1cil de usar incluye nuestro <strong> Servicio de activos de marketing <\/strong> que le brinda acceso a nuestros materiales de marketing m\u00e1s recientes, como fotos, videos y otros dise\u00f1os visuales para ayudarlo el desarrollo de su negocio, adem\u00e1s de proporcionarle conceptos de dise\u00f1o, plantillas y elementos de sitios web actualizados. <\/span><\/p>\n<p><span style=\"color: #ffffff;\"> XBody ejecuta <strong> campa\u00f1as integradas estrat\u00e9gicas <\/strong> globales y locales varias veces al a\u00f1o: nos esforzamos por educar a las personas sobre los beneficios de la capacitaci\u00f3n EMS y la experiencia XBody en particular. <\/span><\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"\/es\/proven-business-models-in-ems\/\">Modelos comerciales<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id: oUv-yT_CJlk -->\t\t\t\t\t\t\t\t<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: oUv-yT_CJlk -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/oUv-yT_CJlk?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins no-margin-bottom noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h3 style=\"text-align: center;\">CRECIMIENTO R\u00c1PIDO EN TODO EL MUNDO<\/h3>\n<p style=\"text-align: center;\"><strong>XBody fue fundado en 2010 y ha estado creciendo desde entonces. Hoy en d\u00eda, es uno de los mayores actores globales en el mercado, ofreciendo valor y la m\u00e1s alta calidad en todos los aspectos.<\/strong><\/p>\n<\/div>\n\t\t\t\t\t<\/div>\n<div  class=\"margins section xbody-changingside post-845  notopspace\">\n\t<div class=\"wide-container\">\n\t\t\t\t<div class=\"story-section\">\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t\t\t\t<div class=\"column w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-two\">\n\t\t\t\t\t\t<div class=\"paragraphcont\">\n\t\t\t\t\t\t\t<h3>Nuestra red mundial de distribuidores<\/h3>\n<p><strong> XBody tiene una red de distribuidores y socios en r\u00e1pido crecimiento en todo el mundo, por lo que no importa d\u00f3nde se encuentre, pronto podr\u00e1 abrir el estudio EMS de sus sue\u00f1os con XBody. <\/strong><\/p>\n<p>No solo recibir\u00e1 los dispositivos de entrenamiento, sino todo el soporte adicional (marketing, negocios, capacitaci\u00f3n, etc.) para que pueda concentrarse en lo m\u00e1s importante: hacer crecer su estudio.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.bisnode.hu\/szolgaltatasok\/bisnode-tanusitvany\/\" target=\"_blank\" rel=\"noopener\"><img style=\"border: 1px solid #CCCCCC;\" title=\" El riesgo de transacciones comerciales con empresas que poseen un Certificado Bisnode es bajo La calificaci\u00f3n se basa en el sistema de calificaci\u00f3n Bisnode que combina cien a\u00f1os de experiencia internacional y considera cientos de variables El Certificado Bisnode indica el estado actual de la empresa que se actualiza diariamente. \" src=\"https:\/\/tanusitvany.bisnode.hu\/Rating\/GetImage?cid=4550955&amp;lang=en&amp;typ=l&amp;bg=FFFFFF&amp;fg=000000\" alt=\"Bisnode tanusitvany\" \/> <\/a><\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"w-col w-col-6 w-col-medium-6 w-col-small-small-stack w-col-tiny-tiny-stack small-order-one\">\n\t\t\t\t\t\t<div class=\"column large\">\n\t\t\t\t\t<!-- youtube_id:  -->\t\t\t\t\t\t\t\t<img class=\"padding-10\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/07\/XBody-World-Map.png\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"accent-bg less-margin margins section\" style=\"padding-top: 42px; padding-bottom: 42px;\">\n\t<div class=\"wide-container\">\n\t\t<div>\n\t\t\t<div class=\"w-row\">\n\t\t\t\n\t\t\t\t<div class=\"w-col w-col-3 w-col-medium-6 w-col-small-small-stack\">\n\t\t\t\t\t<div class=\"flex-2-col\">\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<img class=\"fact-section-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/31-year-e1504009242190.png\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<div class=\"fact-section-header\">7 a\u00f1os<\/div>\n\t\t\t\t\t\t\t<div class=\"fact-section-body\"><p>en la industria EMS<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"w-col w-col-3 w-col-medium-6 w-col-small-small-stack\">\n\t\t\t\t\t<div class=\"flex-2-col\">\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<img class=\"fact-section-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/31-people-e1504009345340.png\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<div class=\"fact-section-header\">60 empleados<\/div>\n\t\t\t\t\t\t\t<div class=\"fact-section-body\"><p>en la Sede<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"w-col w-col-3 w-col-medium-6 w-col-small-small-stack\">\n\t\t\t\t\t<div class=\"flex-2-col\">\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<img class=\"fact-section-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/1-world.png\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<div class=\"fact-section-header\">En 55 pa\u00edses<\/div>\n\t\t\t\t\t\t\t<div class=\"fact-section-body\"><p>en todo el mundo<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t<div class=\"w-col w-col-3 w-col-medium-6 w-col-small-small-stack\">\n\t\t\t\t\t<div class=\"flex-2-col\">\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<img class=\"fact-section-image\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/06\/31-rating-1-e1504009660214.png\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t<div class=\"fact-section-header\">Calificaci\u00f3n AAA<\/div>\n\t\t\t\t\t\t\t<div class=\"fact-section-body\"><p>Reliable&amp;Reputable<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins noborder section\">\n\t\t\t\t\t\t<div class=\"regular-container\"><h3 style=\"text-align: center;\">\u00daNETE A LA FAMILIA XBODY<\/h3>\n<div class=\"xbody_youtube\">\n\t<!-- YoutubeID: m1qPSr7ziHk -->\n\t<div class=\"video-container\"> \n\t\t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/m1qPSr7ziHk?rel=0&amp;controls=0&amp;showinfo=0;start=20\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe> \n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"margins section margins\">\n\t<div class=\"center wide-container\">\n\t\t\t\t<h2 class=\"mb-50 section-heading\">Presentado por<\/h2>\n\t\t\t\t<div class=\"multi-column-wrapper\">\n\t\t\t\t\t\t<a class=\"multi-column w-inline-block product-name\" href=\"#\">\n\t\t\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t\t\t<img class=\"services\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/bodyme.jpg\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"multi-colum-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<a class=\"multi-column w-inline-block product-name\" href=\"#\">\n\t\t\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t\t\t<img class=\"services\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/dailymail.png\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"multi-colum-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<a class=\"multi-column w-inline-block product-name\" href=\"#\">\n\t\t\t\t\t<div class=\"mb-25 multi-column-image-container\">\n\t\t\t\t\t\t<img class=\"services\" src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/Fitnessxx.jpg\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"multi-colum-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"accent-bg margins section xbody-twopost\">\n\t<div class=\"regular-container\">\n\t\t<div class=\"center story-section\">\n\t\t\t<h2 class=\"mb-50 section-heading\">Vamos a ponernos en contacto<\/h2>\n\t\t\t<div class=\"row vertical-align w-row\">\n\t\t\t\t<div class=\"w-col w-col-6 w-col-small-9 w-col-tiny-11\">\n\t\t\t\t\t<div class=\"padded-holder\">\n\t\t\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/np_mail.png\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"intro paragraph\">\u00bfQUIERES SABER M\u00c1S SOBRE LOS DISPOSITIVOS DE ENTRENAMIENTO XBODY EMS?<\/p>\n\t\t\t\t\t\t<p class=\"paragraph\"><p>Cont\u00e1ctenos, responderemos sus preguntas y le daremos un presupuesto personalizado para sus necesidades comerciales.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"solid button\" href=\"https:\/\/es.xbodyworld.com\/es\/contactenos\/\">Cont\u00e1ctenos<\/a>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"w-col w-col-6 w-col-small-9 w-col-tiny-11\">\n\t\t\t\t\t<div class=\"padded-holder\">\n\t\t\t\t\t\t<img src=\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/np_globe.png\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<p class=\"intro paragraph\">\u00bfQUIERES CONVERTIRTE EN DISTRIBUIDOR DE DISPOSITIVOS XBODY EMS?<\/p>\n\t\t\t\t\t\t<p class=\"paragraph\"><p>\u00danase a la familia XBody y solicite derechos para distribuir productos XBody en su pa\u00eds.<\/p>\n<div class=\"maybegluetobottom\">\n\t\t\t\t<a class=\"button\" href=\"https:\/\/es.xbodyworld.com\/es\/convertirse-en-distribuidor-xbody\/\">SOLICITAR DERECHOS DE DISTRIBUCI\u00d3N<\/a>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":".slide.post-399, .slide.post-debug-399 { background-position-x: 100%; background-position-y: 100%; background-size: cover; background-repeat: no-repeat; background-attachment: initial; background-origin: initial; background-clip: initial; background-color: initial; background-image: url(\"https:\/\/es.xbodyworld.com\/wp-content\/uploads\/2017\/05\/xbody-advangate-1.jpg\"); } \u00bfPOR QU\u00c9 XBODY? La misi\u00f3n de XBody es proporcionar siempre a sus socios comerciales conceptos innovadores, \u00fanicos, eficientes, vers\u00e1tiles y rentables en el negocio de EMS. No solo vendemos equipos, sino que tambi\u00e9n [...]","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/397"}],"collection":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/comments?post=397"}],"version-history":[{"count":66,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/397\/revisions"}],"predecessor-version":[{"id":37373,"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/pages\/397\/revisions\/37373"}],"wp:attachment":[{"href":"https:\/\/es.xbodyworld.com\/es\/wp-json\/wp\/v2\/media?parent=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}